{"id":3332,"date":"2024-09-23T10:16:23","date_gmt":"2024-09-23T10:16:23","guid":{"rendered":"https:\/\/www.casafuturs.org\/?post_type=projecte&#038;p=3332"},"modified":"2024-10-01T11:47:26","modified_gmt":"2024-10-01T11:47:26","slug":"restauracion-del-suelo","status":"publish","type":"projecte","link":"https:\/\/www.casafuturs.org\/es\/projecte\/restauracion-del-suelo\/","title":{"rendered":"Restauraci\u00f3n del Suelo"},"content":{"rendered":"<h2><span style=\"font-weight: 400;\">Taller pr\u00e1ctico para ense\u00f1ar m\u00e9todos de evaluaci\u00f3n de la calidad del suelo con tecnolog\u00eda simple.<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">En julio de 2022, La Casa dels Futurs organiz\u00f3 un taller en colaboraci\u00f3n con \"El Refugi\", un huerto comunitario urbano en Barcelona. El evento, titulado \"Un Encuentro con la Tierra\", comparti\u00f3 pr\u00e1cticas de baja tecnolog\u00eda para evaluar y mejorar la salud del suelo. Las participantes fueron invitadas a traer su propio suelo y se les ense\u00f1aron t\u00e1cticas para evaluar su pH y composici\u00f3n. Este taller fue parte de un proyecto en curso para construir redes y pr\u00e1cticas para la resiliencia clim\u00e1tica urbana.\u00a0<\/span><\/p>","protected":false},"featured_media":3333,"parent":0,"template":"","categories":[22],"tags":[],"class_list":["post-3332","projecte","type-projecte","status-publish","has-post-thumbnail","hentry","category-climate-resilience"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.casafuturs.org\/es\/wp-json\/wp\/v2\/projecte\/3332","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.casafuturs.org\/es\/wp-json\/wp\/v2\/projecte"}],"about":[{"href":"https:\/\/www.casafuturs.org\/es\/wp-json\/wp\/v2\/types\/projecte"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.casafuturs.org\/es\/wp-json\/wp\/v2\/media\/3333"}],"wp:attachment":[{"href":"https:\/\/www.casafuturs.org\/es\/wp-json\/wp\/v2\/media?parent=3332"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.casafuturs.org\/es\/wp-json\/wp\/v2\/categories?post=3332"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.casafuturs.org\/es\/wp-json\/wp\/v2\/tags?post=3332"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}